{"id":32503,"date":"2026-09-02T03:12:27","date_gmt":"2026-09-01T20:12:27","guid":{"rendered":"https:\/\/orientalhorology.com\/?post_type=product&#038;p=32503"},"modified":"2026-09-02T03:12:27","modified_gmt":"2026-09-01T20:12:27","slug":"patek-philippe-annual-calendar-grey-dial","status":"publish","type":"product","link":"https:\/\/orientalhorology.com\/en\/product\/patek-philippe-annual-calendar-grey-dial\/","title":{"rendered":"Patek Philippe Annual Calendar Grey Dial"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">\u231a\ufe0fPatek Philippe Annual Calendar Grey Dial<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ref. 5146J<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\ud83c\udf1f \u0e2a\u0e20\u0e32\u0e1e\u0e2a\u0e27\u0e22 \u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e04\u0e23\u0e1a Full-set \u0e1b\u0e35 2013 \u0e04\u0e23\u0e1a\u0e22\u0e31\u0e19\u0e1b\u0e49\u0e32\u0e22 Tag \u0e1a\u0e31\u0e04\u0e40\u0e04\u0e34\u0e49\u0e25\u0e2d\u0e31\u0e1e\u0e40\u0e01\u0e23\u0e14\u0e21\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e1a\u0e32\u0e19\u0e1e\u0e31\u0e1a\u0e01\u0e25\u0e21 \u0e2b\u0e19\u0e49\u0e32\u0e40\u0e17\u0e32 \u0e2b\u0e32\u0e22\u0e32\u0e01\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\ud83c\udf1f \u0e40\u0e23\u0e37\u0e2d\u0e19\u0e40\u0e27\u0e25\u0e32\u0e2d\u0e31\u0e19\u0e07\u0e14\u0e07\u0e32\u0e21\u0e41\u0e25\u0e30\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a\u0e17\u0e38\u0e01\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e27\u0e32\u0e07\u0e1a\u0e19\u0e2b\u0e19\u0e49\u0e32\u0e1b\u0e31\u0e14 \u0e21\u0e32\u0e43\u0e19\u0e15\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 18K Yellow Gold \u0e02\u0e19\u0e32\u0e14 39 mm \u0e2b\u0e19\u0e49\u0e32\u0e1b\u0e31\u0e14\u0e2a\u0e35 Slate Grey \u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e1f\u0e31\u0e07\u0e01\u0e4c\u0e0a\u0e31\u0e19 Annual Calendar, Moonphase \u0e41\u0e25\u0e30 Power Reserve Indicator \u0e17\u0e35\u0e48\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e48\u0e32\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e0a\u0e31\u0e14\u0e40\u0e08\u0e19 \u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e14\u0e49\u0e27\u0e22\u0e01\u0e25\u0e44\u0e01\u0e2d\u0e31\u0e15\u0e42\u0e19\u0e21\u0e31\u0e15\u0e34 Calibre 324 S IRM QA LU \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e2a\u0e33\u0e23\u0e2d\u0e07\u0e1e\u0e25\u0e31\u0e07\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 45 \u0e0a\u0e31\u0e48\u0e27\u0e42\u0e21\u0e07 \u0e40\u0e1b\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19 Complications \u0e02\u0e2d\u0e07 Patek Philippe \u0e17\u0e35\u0e48\u0e1c\u0e2a\u0e21\u0e1c\u0e2a\u0e32\u0e19\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e07\u0e48\u0e32\u0e07\u0e32\u0e21 \u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e07\u0e32\u0e19\u0e08\u0e23\u0e34\u0e07 \u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e04\u0e25\u0e32\u0e2a\u0e2a\u0e34\u0e01\u0e40\u0e2b\u0e19\u0e37\u0e2d\u0e01\u0e32\u0e25\u0e40\u0e27\u0e25\u0e32\u0e44\u0e27\u0e49\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e25\u0e07\u0e15\u0e31\u0e27 \u0e2a\u0e27\u0e22\u0e02\u0e36\u0e49\u0e19\u0e02\u0e49\u0e2d\u0e2a\u0e38\u0e14\u0e46\u0e04\u0e23\u0e31\u0e1a<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\ud83d\udccc \u0e40\u0e2a\u0e19\u0e2d\u0e23\u0e32\u0e04\u0e32\u0e14\u0e35\u0e46\u0e17\u0e35\u0e48 929,000 \u0e1a\u0e32\u0e17<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">\u263a\ufe0f\u0e1a\u0e2d\u0e15 \u0e23\u0e31\u0e1a\u0e0b\u0e37\u0e49\u0e2d\/\u0e40\u0e17\u0e23\u0e14 \u0e14\u0e49\u0e27\u0e22\u0e19\u0e30\u0e04\u0e23\u0e31\u0e1a \u0e43\u0e04\u0e23\u0e21\u0e35\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e44\u0e2b\u0e19\u0e2d\u0e22\u0e32\u0e01\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e31\u0e19\u0e17\u0e31\u0e01\u0e21\u0e32\u0e04\u0e38\u0e22\u0e2b\u0e25\u0e31\u0e07\u0e44\u0e21\u0e04\u0e4c\u0e44\u0e14\u0e49\u0e40\u0e25\u0e22\u0e04\u0e23\u0e31\u0e1a\u263a\ufe0f<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"p1\"><span class=\"s1\">\u231a\ufe0fPatek Philippe Annual Calendar Grey Dial<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Ref. 5146J<\/span><\/p>\n","protected":false},"featured_media":32504,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[21],"product_tag":[],"class_list":{"0":"post-32503","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-patek-philippe","8":"first","9":"instock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/product\/32503","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/comments?post=32503"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/media\/32504"}],"wp:attachment":[{"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/media?parent=32503"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/product_brand?post=32503"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/product_cat?post=32503"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/orientalhorology.com\/en\/wp-json\/wp\/v2\/product_tag?post=32503"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}